{"id":8854,"date":"2022-09-09T13:21:10","date_gmt":"2022-09-09T13:21:10","guid":{"rendered":"http:\/\/dummy.xtemos.com\/woodmart2\/accessories-elementor\/?p=8854"},"modified":"2022-09-09T13:21:10","modified_gmt":"2022-09-09T13:21:10","slug":"minimalist-japanese-inspired-furniture","status":"publish","type":"post","link":"https:\/\/carnace.com\/index.php\/2022\/09\/09\/minimalist-japanese-inspired-furniture\/","title":{"rendered":"Minimalist Japanese-inspired furniture"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"8854\" class=\"elementor elementor-8854\" data-elementor-post-type=\"post\">\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"wd-negative-gap elementor-element elementor-element-8871389 e-flex e-con-boxed e-con e-parent\" data-id=\"8871389\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-99ab3e5 elementor-widget elementor-widget-wd_text_block\" data-id=\"99ab3e5\" data-element_type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left\">\n\t\t\t\n\t\t\t<p>A taciti cras scelerisque scelerisque gravida natoque nulla vestibulum turpis primis adipiscing faucibus scelerisque adipiscing aliquet pretium.\u00a0Et iaculis mi velit tincidunt vestibulum a duis tempor non magna ultrices porta malesuada ullamcorper scelerisque parturient himenaeos iaculis sit.\u00a0Scelerisque sociosqu ullamcorper urna nisl mollis vestibulum pretium commodo inceptos.<\/p><p>Ac ullamcorper a ultrices a a urna ac commodo nam condimentum parturient.\u00a0Libero suspendisse facilisis parturient elementum curabitur.\u00a0Erat a per dis aliquet ultricies curabitur nostra suspendisse nec adipiscing donec vestibulum a parturient a ac ut non adipiscing penatibus nec erat.\u00a0A at nec rutrum nam molestie suspendisse scelerisque platea a ut commodo volutpat ullamcorper.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc8d32f wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"dc8d32f\" data-element_type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"title-wrapper set-mb-s reset-last-child wd-title-color-primary wd-title-style-default wd-title-size-default text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-l wd-underline-colored\"><u>5.<\/u> Eva Solo: Danish Furnishing Accessories<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"wd-negative-gap elementor-element elementor-element-1c01875 e-flex e-con-boxed e-con e-parent\" data-id=\"1c01875\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-4b1b10c e-con-full e-flex e-con e-child\" data-id=\"4b1b10c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ce010b3 wd-width-100 elementor-widget elementor-widget-wd_images_gallery\" data-id=\"ce010b3\" data-element_type=\"widget\" data-widget_type=\"wd_images_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wd-images-gallery photoswipe-images\" style=\"--wd-align-items:center; --wd-justify-content:center;\">\n\t\t\t\t\t\t<div class=\"wd-grid-g\" style=\"--wd-col-lg:2;--wd-col-md:2;--wd-col-sm:2;--wd-gap-lg:10px;\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-blog-img-1.jpg\"data-width=\"1200\" data-height=\"742\" data-index=\"1\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-blog-img-1-400x400.jpg\"alt=\"accessories-blog-img-1\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-blog-img-2.jpg\"data-width=\"1200\" data-height=\"742\" data-index=\"2\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-blog-img-2-400x400.jpg\"alt=\"accessories-blog-img-2\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-blog-img-3.jpg\"data-width=\"1200\" data-height=\"742\" data-index=\"3\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-blog-img-3-400x400.jpg\"alt=\"accessories-blog-img-3\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-blog-img-4.jpg\"data-width=\"1200\" data-height=\"742\" data-index=\"4\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-blog-img-4-400x400.jpg\"alt=\"accessories-blog-img-4\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-fb0468f e-con-full e-flex e-con e-child\" data-id=\"fb0468f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0c866e7 elementor-widget elementor-widget-wd_text_block\" data-id=\"0c866e7\" data-element_type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left\">\n\t\t\t\n\t\t\t<p>Purus lobortis senectus faucibus imperdiet rutrum porttitor tincidunt laoreet parturient consectetur tortor ad adipiscing id a duis hendrerit diam. A at nec rutrum nam molestie suspendisse scelerisque platea a ut commodo volutpat ullamcorper penatibus dis quis felis justo porta montes nam a vestibulum tristique parturient parturient eget tincidunt.Semper dui.<\/p><blockquote><p>Scelerisque leo fusce dui parturient ad a penatibus mauris adipiscing tempus vestibulum imperdiet gravida magnis a nec penatibus augue ullamcorper quis sem a luctus leo eros ornare.<\/p><\/blockquote><p>Cum scelerisque montes conubia vivamus volutpat consectetur euismod ullamcorper netus quis dui vestibulum hac lorem parturient a massa parturient cubilia cubilia mauris elementum. Condimentum condimentum hac egestas a dictumst potenti.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"wd-negative-gap elementor-element elementor-element-4e51057 e-flex e-con-boxed e-con e-parent\" data-id=\"4e51057\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-381123a elementor-widget elementor-widget-wd_text_block\" data-id=\"381123a\" data-element_type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left\">\n\t\t\t\n\t\t\t<p>Purus lobortis senectus faucibus imperdiet rutrum porttitor tincidunt laoreet parturient consectetur tortor ad adipiscing id a duis hendrerit diam. A at nec rutrum nam molestie suspendisse scelerisque platea a ut commodo volutpat ullamcorper penatibus dis quis felis justo porta montes nam a vestibulum tristique parturient parturient eget tincidunt. Semper dui.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34ba1d5 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"34ba1d5\" data-element_type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"title-wrapper set-mb-s reset-last-child wd-title-color-primary wd-title-style-default wd-title-size-default text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-l wd-underline-colored\"><u>4.<\/u> Magisso Finnish Design Movement<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"wd-negative-gap elementor-element elementor-element-e434be5 e-flex e-con-boxed e-con e-parent\" data-id=\"e434be5\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-9702e61 e-con-full e-flex e-con e-child\" data-id=\"9702e61\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-58e2fe5 elementor-widget elementor-widget-wd_text_block\" data-id=\"58e2fe5\" data-element_type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left\">\n\t\t\t\n\t\t\t<div id=\"wd-616929f324bdf\" class=\"wd-text-block wd-wpb reset-last-child wd-rs-616929f324bdf text-left \"><p>Purus lobortis senectus faucibus imperdiet rutrum porttitor tincidunt laoreet parturient consectetur tortor ad adipiscing id a duis hendrerit diam. A at nec rutrum nam molestie suspendisse scelerisque platea a ut commodo volutpat ullamcorper penatibus dis quis felis justo porta montes nam a vestibulum tristique parturient parturient eget tincidunt. Semper dui.<\/p><p>Cum scelerisque montes conubia vivamus volutpat consectetur euismod ullamcorper netus quis dui vestibulum hac lorem parturient a massa parturient cubilia cubilia mauris elementum. Condimentum condimentum hac egestas a dictumst potenti.<\/p><\/div><div id=\"wd-61692a20df8a5\" class=\"wd-text-block wd-wpb reset-last-child wd-rs-61692a20df8a5 text-left wd-fontsize-s font-primary \"><p><em>Scelerisque leo fusce dui parturient ad a penatibus mauris adipiscing tempus vestibulum imperdiet gravida magnis a nec penatibus augue ullamcorper quis sem a luctus leo eros ornare cubilia mauris elementum imperdiet tincidunt.<\/em><\/p><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-19934da e-con-full e-flex e-con e-child\" data-id=\"19934da\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5771462 wd-width-100 elementor-widget elementor-widget-wd_images_gallery\" data-id=\"5771462\" data-element_type=\"widget\" data-widget_type=\"wd_images_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wd-images-gallery photoswipe-images\" style=\"--wd-align-items:center; --wd-justify-content:center;\">\n\t\t\t\t\t\t<div class=\"wd-grid-g\" style=\"--wd-col-lg:2;--wd-col-md:2;--wd-col-sm:2;--wd-gap-lg:10px;\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-single-post-img-8-opt.jpg\"data-width=\"1200\" data-height=\"742\" data-index=\"1\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-single-post-img-8-opt-400x400.jpg\"alt=\"accessories-single-post-img-8-opt\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-single-post-img-7-opt.jpg\"data-width=\"1200\" data-height=\"742\" data-index=\"2\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-single-post-img-7-opt-400x400.jpg\"alt=\"accessories-single-post-img-7-opt\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-single-post-img-3-opt.jpg\"data-width=\"1200\" data-height=\"742\" data-index=\"3\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-single-post-img-3-opt-400x400.jpg\"alt=\"accessories-single-post-img-3-opt\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-single-post-img-1-opt.jpg\"data-width=\"1200\" data-height=\"742\" data-index=\"4\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-single-post-img-1-opt-400x400.jpg\"alt=\"accessories-single-post-img-1-opt\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"wd-negative-gap elementor-element elementor-element-6fa79a4 e-flex e-con-boxed e-con e-parent\" data-id=\"6fa79a4\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1b7dbd8 elementor-widget elementor-widget-wd_text_block\" data-id=\"1b7dbd8\" data-element_type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left\">\n\t\t\t\n\t\t\t<p>Purus lobortis senectus faucibus imperdiet rutrum porttitor tincidunt laoreet parturient consectetur tortor ad adipiscing id a duis hendrerit diam. A at nec rutrum nam molestie suspendisse scelerisque platea a ut commodo volutpat ullamcorper penatibus dis quis felis justo porta montes nam a vestibulum tristique parturient parturient eget tincidunt. Semper dui.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79800fa wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"79800fa\" data-element_type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"title-wrapper set-mb-s reset-last-child wd-title-color-primary wd-title-style-default wd-title-size-default text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-l wd-underline-colored\"><u>3.<\/u> R\u00f6shults Svenska Hantverk<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"wd-negative-gap elementor-element elementor-element-f2674b5 e-flex e-con-boxed e-con e-parent\" data-id=\"f2674b5\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-1365f79 e-con-full e-flex e-con e-child\" data-id=\"1365f79\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8ad8ead wd-width-100 elementor-widget elementor-widget-wd_images_gallery\" data-id=\"8ad8ead\" data-element_type=\"widget\" data-widget_type=\"wd_images_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wd-images-gallery photoswipe-images\" style=\"--wd-align-items:center; --wd-justify-content:center;\">\n\t\t\t\t\t\t<div class=\"wd-grid-g\" style=\"--wd-col-lg:2;--wd-col-md:2;--wd-col-sm:2;--wd-gap-lg:10px;\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-blog-img-9.jpg\"data-width=\"1200\" data-height=\"742\" data-index=\"1\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-blog-img-9-400x400.jpg\"alt=\"accessories-blog-img-9\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-blog-img-8.jpg\"data-width=\"1200\" data-height=\"742\" data-index=\"2\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-blog-img-8-400x400.jpg\"alt=\"accessories-blog-img-8\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-blog-img-7.jpg\"data-width=\"1200\" data-height=\"742\" data-index=\"3\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-blog-img-7-400x400.jpg\"alt=\"accessories-blog-img-7\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-blog-img-5.jpg\"data-width=\"1200\" data-height=\"742\" data-index=\"4\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-blog-img-5-400x400.jpg\"alt=\"accessories-blog-img-5\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-5592d19 e-con-full e-flex e-con e-child\" data-id=\"5592d19\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-14e0179 elementor-widget elementor-widget-wd_text_block\" data-id=\"14e0179\" data-element_type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left\">\n\t\t\t\n\t\t\t<p>Purus lobortis senectus faucibus imperdiet rutrum porttitor tincidunt laoreet parturient consectetur tortor ad adipiscing id a duis hendrerit diam. A at nec rutrum nam molestie suspendisse scelerisque platea a ut commodo volutpat ullamcorper penatibus\u00a0dis quis felis justo porta montes nam a vestibulum tristique parturient parturient eget tincidunt. Semper dui.<\/p><p><img decoding=\"async\" class=\"wp-image-8938 alignleft\" src=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/brand-alessi.png\" alt=\"\" width=\"120\" height=\"67\" srcset=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/brand-alessi.png 180w, https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/brand-alessi-148x82.png 148w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/>Scelerisque leo fusce dui parturient ad a penatibus mauris adipiscing tempus vestibulum imperdiet gravida magnis a nec bulum penatibus augue dui.<\/p><p>Cum scelerisque montes conubia vivamus volutpat consectetur euismod ullamcorper netus quis dui vestibulum hac lorem parturient a massa parturient cubilia cubilia mauris elementum. Condimentum condimentum hac egestas a dictumst potenti.\u00a0Rutrum nam molestie suspendisse scelerisque platea.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"wd-negative-gap elementor-element elementor-element-a98b8bd e-flex e-con-boxed e-con e-parent\" data-id=\"a98b8bd\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6af6bd1 elementor-widget elementor-widget-wd_text_block\" data-id=\"6af6bd1\" data-element_type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left\">\n\t\t\t\n\t\t\t<p>Purus lobortis senectus faucibus imperdiet rutrum porttitor tincidunt laoreet parturient consectetur tortor ad adipiscing id a duis hendrerit diam. A at nec rutrum nam molestie suspendisse scelerisque platea a ut commodo volutpat ullamcorper penatibus dis quis felis justo porta montes nam a vestibulum tristique parturient parturient eget tincidunt. Semper dui.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fd41c3 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"3fd41c3\" data-element_type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"title-wrapper set-mb-s reset-last-child wd-title-color-primary wd-title-style-default wd-title-size-default text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-l wd-underline-colored\"><u>2.<\/u> Alessi: the Italian Factory of Design<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"wd-negative-gap elementor-element elementor-element-59726ec e-flex e-con-boxed e-con e-parent\" data-id=\"59726ec\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-cb2f091 e-con-full e-flex e-con e-child\" data-id=\"cb2f091\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-89b21a3 elementor-widget elementor-widget-wd_text_block\" data-id=\"89b21a3\" data-element_type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left\">\n\t\t\t\n\t\t\t<div id=\"wd-616929f324bdf\" class=\"wd-text-block wd-wpb reset-last-child wd-rs-616929f324bdf text-left \"><p>Purus lobortis senectus faucibus imperdiet rutrum porttitor tincidunt laoreet parturient consectetur tortor ad adipiscing id a duis hendrerit diam. A at nec rutrum nam molestie suspendisse scelerisque platea a ut commodo volutpat ullamcorper penatibus dis quis felis justo porta montes nam a vestibulum tristique parturient parturient eget tincidunt. Semper dui.<\/p><p class=\"font-title\" style=\"font-style: italic; font-size: 18px; color: #4a4a4a;\">Scelerisque leo fusce dui parturient ad a penatibus mauris adipiscing tempus vestibulum imperdiet gravida magnis a nec penatibus augue ullamcorper quis sem a luctus leo eros ornare cubilia mauris elementum imperdiet tincidunt.<\/p><p>Cum scelerisque montes conubia vivamus volutpat consectetur euismod ullamcorper netus quis dui vestibulum hac lorem parturient a massa parturient cubilia cubilia mauris elementum. Condimentum condimentum hac egestas a dictumst potenti.<\/p><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-f462a56 e-con-full e-flex e-con e-child\" data-id=\"f462a56\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-edbc552 wd-width-100 elementor-widget elementor-widget-wd_images_gallery\" data-id=\"edbc552\" data-element_type=\"widget\" data-widget_type=\"wd_images_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wd-images-gallery photoswipe-images\" style=\"--wd-align-items:center; --wd-justify-content:center;\">\n\t\t\t\t\t\t<div class=\"wd-grid-g\" style=\"--wd-col-lg:2;--wd-col-md:2;--wd-col-sm:2;--wd-gap-lg:10px;\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-blog-img-1.jpg\"data-width=\"1200\" data-height=\"742\" data-index=\"1\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-blog-img-1-400x400.jpg\"alt=\"accessories-blog-img-1\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-blog-img-2.jpg\"data-width=\"1200\" data-height=\"742\" data-index=\"2\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-blog-img-2-400x400.jpg\"alt=\"accessories-blog-img-2\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-blog-img-3.jpg\"data-width=\"1200\" data-height=\"742\" data-index=\"3\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-blog-img-3-400x400.jpg\"alt=\"accessories-blog-img-3\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-blog-img-4.jpg\"data-width=\"1200\" data-height=\"742\" data-index=\"4\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-blog-img-4-400x400.jpg\"alt=\"accessories-blog-img-4\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"wd-negative-gap elementor-element elementor-element-689f940 e-flex e-con-boxed e-con e-parent\" data-id=\"689f940\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4ed0a75 elementor-widget elementor-widget-wd_text_block\" data-id=\"4ed0a75\" data-element_type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left\">\n\t\t\t\n\t\t\t<p>Purus lobortis senectus faucibus imperdiet rutrum porttitor tincidunt laoreet parturient consectetur tortor ad adipiscing id a duis hendrerit diam. A at nec rutrum nam molestie suspendisse scelerisque platea a ut commodo volutpat ullamcorper penatibus dis quis felis justo porta montes nam a vestibulum tristique parturient parturient eget tincidunt. Semper dui.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7ffea6 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"f7ffea6\" data-element_type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"title-wrapper set-mb-s reset-last-child wd-title-color-primary wd-title-style-default wd-title-size-default text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-l wd-underline-colored\"><u>1.<\/u> Leolux Design Furniture<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-faeba48 wd-width-100 elementor-widget elementor-widget-wd_images_gallery\" data-id=\"faeba48\" data-element_type=\"widget\" data-widget_type=\"wd_images_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wd-images-gallery photoswipe-images\" style=\"--wd-align-items:center; --wd-justify-content:center;\">\n\t\t\t\t\t\t<div class=\"wd-grid-g\" style=\"--wd-col-lg:3;--wd-col-md:2;--wd-col-sm:2;--wd-gap-lg:10px;\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-single-post-img-2-opt.jpg\"data-width=\"1200\" data-height=\"742\" data-index=\"1\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-single-post-img-2-opt-400x400.jpg\"alt=\"accessories-single-post-img-2-opt\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-single-post-img-4-opt.jpg\"data-width=\"1200\" data-height=\"742\" data-index=\"2\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-single-post-img-4-opt-400x400.jpg\"alt=\"accessories-single-post-img-4-opt\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-single-post-img-6-opt.jpg\"data-width=\"1200\" data-height=\"742\" data-index=\"3\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-single-post-img-6-opt-400x400.jpg\"alt=\"accessories-single-post-img-6-opt\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-single-post-img-7-opt.jpg\"data-width=\"1200\" data-height=\"742\" data-index=\"4\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-single-post-img-7-opt-400x400.jpg\"alt=\"accessories-single-post-img-7-opt\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-single-post-img-9-opt.jpg\"data-width=\"1200\" data-height=\"742\" data-index=\"5\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-single-post-img-9-opt-400x400.jpg\"alt=\"accessories-single-post-img-9-opt\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-single-post-img-8-opt.jpg\"data-width=\"1200\" data-height=\"742\" data-index=\"6\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/accessories-single-post-img-8-opt-400x400.jpg\"alt=\"accessories-single-post-img-8-opt\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2f8bff elementor-widget elementor-widget-wd_text_block\" data-id=\"f2f8bff\" data-element_type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left\">\n\t\t\t\n\t\t\t<p>Ullamcorper per dis adipiscing curae nisl nisl blandit nunc vel massa ad venenatis a cras donec adipiscing adipiscing at a suspendisse montes habitasse vestibulum et sagittis aptent ornare. Purus nostra orci nascetur ante aenean parturient nullam conubia parturient a porta felis dapibus potenti magna turpis a vestibulum nunc a vestibulum at parturient leo feugiat a.<\/p><blockquote><p>Scelerisque a vulputate varius duis a purus nam integer lacus ridiculus ullamcorper nec ac convallis mus hac parturient hendrerit erat a aliquam amet. Cras duis aliquet a cras hendrerit adipiscing maecenas adipiscing scelerisque mi parturient nostra urna non.Iaculis ornare vitae convallis duis ut tempus odio suspendisse adipiscing potenti vivamus odio eget a adipiscing hac.<\/p><\/blockquote><p>At habitant amet erat gravida lectus dapibus parturient per in praesent condimentum adipiscing gravida interdum rhoncus arcu condimentum dui scelerisque ipsum montes montes id a a.In tempor a a eu etiam per habitant dis condimentum vestibulum augue vivamus massa ullamcorper suspendisse tellus condimentum enim nunc varius sem dis.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a58d995 elementor-widget elementor-widget-wd_products_brands\" data-id=\"a58d995\" data-element_type=\"widget\" data-widget_type=\"wd_products_brands.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wd-brands brands-widget slider-brands_2341 wd-hover-default wd-style-default wd-layout-carousel wd-carousel-container\" id=\"brands_2341\">\n\t\t\t\t\t\t\t<div class=\"wd-carousel-inner\">\n\t\t\t\n\t\t\t<div class=\"wd-carousel wd-grid\" data-scroll_per_page=\"yes\" style=\"--wd-col-lg:5;--wd-col-md:4;--wd-col-sm:2;\">\n\t\t\t\t\t\t\t\t\t<div class=\"wd-carousel-wrap\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t<div class=\"wd-brand-item brand-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a title=\"Xiaomi\" href=\"https:\/\/carnace.com\/index.php\/shop\/?filter_brand=xiaomi\" class=\"wd-fill\"><\/a>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"180\" height=\"100\" src=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/w-accessories-brand-5.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/w-accessories-brand-5.png 180w, https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/w-accessories-brand-5-148x82.png 148w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t<div class=\"wd-brand-item brand-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a title=\"Spigen\" href=\"https:\/\/carnace.com\/index.php\/shop\/?filter_brand=spigen\" class=\"wd-fill\"><\/a>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"180\" height=\"100\" src=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/w-accessories-brand-6.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/w-accessories-brand-6.png 180w, https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/w-accessories-brand-6-148x82.png 148w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t<div class=\"wd-brand-item brand-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a title=\"Samsung\" href=\"https:\/\/carnace.com\/index.php\/shop\/?filter_brand=samsung\" class=\"wd-fill\"><\/a>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"180\" height=\"100\" src=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/w-accessories-brand-3.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/w-accessories-brand-3.png 180w, https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/w-accessories-brand-3-148x82.png 148w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t<div class=\"wd-brand-item brand-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a title=\"Panasonic\" href=\"https:\/\/carnace.com\/index.php\/shop\/?filter_brand=panasonic\" class=\"wd-fill\"><\/a>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"180\" height=\"100\" src=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/w-accessories-brand-1.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/w-accessories-brand-1.png 180w, https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/w-accessories-brand-1-148x82.png 148w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t<div class=\"wd-brand-item brand-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a title=\"Nillkin\" href=\"https:\/\/carnace.com\/index.php\/shop\/?filter_brand=nillkin\" class=\"wd-fill\"><\/a>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"180\" height=\"100\" src=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/w-accessories-brand-8.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/w-accessories-brand-8.png 180w, https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/w-accessories-brand-8-148x82.png 148w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t<div class=\"wd-brand-item brand-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a title=\"Logitech\" href=\"https:\/\/carnace.com\/index.php\/shop\/?filter_brand=logitech\" class=\"wd-fill\"><\/a>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"180\" height=\"100\" src=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/w-accessories-brand-2.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/w-accessories-brand-2.png 180w, https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/w-accessories-brand-2-148x82.png 148w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t<div class=\"wd-brand-item brand-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a title=\"Huawei\" href=\"https:\/\/carnace.com\/index.php\/shop\/?filter_brand=huawei\" class=\"wd-fill\"><\/a>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"180\" height=\"100\" src=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/w-accessories-brand-10.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/w-accessories-brand-10.png 180w, https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/w-accessories-brand-10-148x82.png 148w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t<div class=\"wd-brand-item brand-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a title=\"Energizer\" href=\"https:\/\/carnace.com\/index.php\/shop\/?filter_brand=energizer\" class=\"wd-fill\"><\/a>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"180\" height=\"100\" src=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/w-accessories-brand-11.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/w-accessories-brand-11.png 180w, https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/w-accessories-brand-11-148x82.png 148w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t<div class=\"wd-brand-item brand-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a title=\"Ecoflow\" href=\"https:\/\/carnace.com\/index.php\/shop\/?filter_brand=ecoflow\" class=\"wd-fill\"><\/a>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"180\" height=\"100\" src=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/w-accessories-brand-12.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/w-accessories-brand-12.png 180w, https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/w-accessories-brand-12-148x82.png 148w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t<div class=\"wd-brand-item brand-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a title=\"Belkin\" href=\"https:\/\/carnace.com\/index.php\/shop\/?filter_brand=belkin\" class=\"wd-fill\"><\/a>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"180\" height=\"100\" src=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/w-accessories-brand-9.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/w-accessories-brand-9.png 180w, https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/w-accessories-brand-9-148x82.png 148w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t<div class=\"wd-brand-item brand-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a title=\"Baseus\" href=\"https:\/\/carnace.com\/index.php\/shop\/?filter_brand=baseus\" class=\"wd-fill\"><\/a>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"180\" height=\"100\" src=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/w-accessories-brand-4.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/w-accessories-brand-4.png 180w, https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/w-accessories-brand-4-148x82.png 148w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t<div class=\"wd-brand-item brand-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a title=\"Anker\" href=\"https:\/\/carnace.com\/index.php\/shop\/?filter_brand=anker\" class=\"wd-fill\"><\/a>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"180\" height=\"100\" src=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/w-accessories-brand-7.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/w-accessories-brand-7.png 180w, https:\/\/carnace.com\/wp-content\/uploads\/2022\/09\/w-accessories-brand-7-148x82.png 148w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6326c26 elementor-widget elementor-widget-wd_button\" data-id=\"6326c26\" data-element_type=\"widget\" data-widget_type=\"wd_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wd-button-wrapper text-center\" >\n\t\t\t<a class=\"btn btn-style-bordered btn-style-rectangle btn-size-default btn-color-default btn-icon-pos-right\"  href=\"#\">\n\t\t\t\t<span class=\"wd-btn-text\" data-elementor-setting-key=\"text\">\n\t\t\t\t\tVIEW ALL BRANDS\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>A taciti cras scelerisque scelerisque gravida natoque nulla vestibulum turpis primis adipiscing faucibus scelerisque adipiscing aliquet pretium.\u00a0Et iaculis mi velit<\/p>\n","protected":false},"author":1,"featured_media":8855,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[41,44,45],"class_list":["post-8854","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inspiration","tag-chair","tag-inspiratio","tag-news"],"_links":{"self":[{"href":"https:\/\/carnace.com\/index.php\/wp-json\/wp\/v2\/posts\/8854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/carnace.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/carnace.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/carnace.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/carnace.com\/index.php\/wp-json\/wp\/v2\/comments?post=8854"}],"version-history":[{"count":0,"href":"https:\/\/carnace.com\/index.php\/wp-json\/wp\/v2\/posts\/8854\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/carnace.com\/index.php\/wp-json\/wp\/v2\/media\/8855"}],"wp:attachment":[{"href":"https:\/\/carnace.com\/index.php\/wp-json\/wp\/v2\/media?parent=8854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/carnace.com\/index.php\/wp-json\/wp\/v2\/categories?post=8854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/carnace.com\/index.php\/wp-json\/wp\/v2\/tags?post=8854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}